{"id":88854,"date":"2025-10-29T15:10:13","date_gmt":"2025-10-29T14:10:13","guid":{"rendered":"https:\/\/www.ohis.be\/produit\/rondselas-set-n25-w25x545-eukdh-6\/"},"modified":"2025-10-30T13:31:06","modified_gmt":"2025-10-30T12:31:06","slug":"rondselas-set-n25-w25x545-eukdh-6","status":"publish","type":"product","link":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/","title":{"rendered":"Rondselas set N25\/W25x545-EU+KDH 6"},"content":{"rendered":"<p>Rondselas set N25\/W25x545-EU+KDH 6<\/p>\n<p>&#8211; Aandrijfas W25X 545<\/p>\n<p>&#8211; Tandwiel met bus<\/p>\n<p>&#8211; Stelschroef M10 X 12<\/p>\n<p>&#8211; Aanslagring A 25\/ 45X18<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rondselas set N25\/W25x545-EU+KDH 6<\/p>\n","protected":false},"featured_media":88737,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[360],"product_tag":[],"class_list":{"0":"post-88854","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-demag-dh-nl","7":"yith_product_brand-demag-nl","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rondselas set N25\/W25x545-EU+KDH 6 - Ohis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rondselas set N25\/W25x545-EU+KDH 6 - Ohis\" \/>\n<meta property=\"og:description\" content=\"Rondselas set N25\/W25x545-EU+KDH 6\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Ohis\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:31:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/10\/g_75210933-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/\",\"name\":\"Rondselas set N25\\\/W25x545-EU+KDH 6 - Ohis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/g_75210933-scaled.jpg\",\"datePublished\":\"2025-10-29T14:10:13+00:00\",\"dateModified\":\"2025-10-30T12:31:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/g_75210933-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/g_75210933-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Kit arbre \u00e0 pignon N25\\\/W25x545-EU+KDH 6\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/produit\\\/rondselas-set-n25-w25x545-eukdh-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/producten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rondselas set N25\\\/W25x545-EU+KDH 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/\",\"name\":\"Ohis\",\"description\":\"Outils de levage\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/#organization\",\"name\":\"Ohis\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-ohis-wit.svg\",\"contentUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-ohis-wit.svg\",\"caption\":\"Ohis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rondselas set N25\/W25x545-EU+KDH 6 - Ohis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/","og_locale":"nl_NL","og_type":"article","og_title":"Rondselas set N25\/W25x545-EU+KDH 6 - Ohis","og_description":"Rondselas set N25\/W25x545-EU+KDH 6","og_url":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/","og_site_name":"Ohis","article_modified_time":"2025-10-30T12:31:06+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/10\/g_75210933-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/","url":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/","name":"Rondselas set N25\/W25x545-EU+KDH 6 - Ohis","isPartOf":{"@id":"https:\/\/www.ohis.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/#primaryimage"},"image":{"@id":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/10\/g_75210933-scaled.jpg","datePublished":"2025-10-29T14:10:13+00:00","dateModified":"2025-10-30T12:31:06+00:00","breadcrumb":{"@id":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/#primaryimage","url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/10\/g_75210933-scaled.jpg","contentUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/10\/g_75210933-scaled.jpg","width":2560,"height":1920,"caption":"Kit arbre \u00e0 pignon N25\/W25x545-EU+KDH 6"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ohis.be\/nl\/produit\/rondselas-set-n25-w25x545-eukdh-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ohis.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/www.ohis.be\/nl\/producten\/"},{"@type":"ListItem","position":3,"name":"Rondselas set N25\/W25x545-EU+KDH 6"}]},{"@type":"WebSite","@id":"https:\/\/www.ohis.be\/nl\/#website","url":"https:\/\/www.ohis.be\/nl\/","name":"Ohis","description":"Outils de levage","publisher":{"@id":"https:\/\/www.ohis.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ohis.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.ohis.be\/nl\/#organization","name":"Ohis","url":"https:\/\/www.ohis.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.ohis.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2021\/02\/logo-ohis-wit.svg","contentUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2021\/02\/logo-ohis-wit.svg","caption":"Ohis"},"image":{"@id":"https:\/\/www.ohis.be\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/product\/88854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/media\/88737"}],"wp:attachment":[{"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/media?parent=88854"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/product_brand?post=88854"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/product_cat?post=88854"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ohis.be\/nl\/wp-json\/wp\/v2\/product_tag?post=88854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}