{"id":84768,"date":"2025-08-20T15:54:24","date_gmt":"2025-08-20T13:54:24","guid":{"rendered":"https:\/\/www.ohis.be\/produit\/suspension-plate-kbk-a12-16\/"},"modified":"2025-08-25T13:20:26","modified_gmt":"2025-08-25T11:20:26","slug":"suspension-plate-kbk-a12-16","status":"publish","type":"product","link":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/","title":{"rendered":"Suspension plate KBK A12\/16"},"content":{"rendered":"<p>Suspension plate KBK A12\/16<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suspension plate KBK A12\/16<\/p>\n","protected":false},"featured_media":84244,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[143],"product_tag":[],"class_list":{"0":"post-84768","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-demag-kbk-en","7":"yith_product_brand-demag-en","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suspension plate KBK A12\/16 - Ohis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspension plate KBK A12\/16 - Ohis\" \/>\n<meta property=\"og:description\" content=\"Suspension plate KBK A12\/16\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Ohis\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T11:20:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/08\/g_85502044.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/\",\"name\":\"Suspension plate KBK A12\\\/16 - Ohis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/g_85502044.jpg\",\"datePublished\":\"2025-08-20T13:54:24+00:00\",\"dateModified\":\"2025-08-25T11:20:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/g_85502044.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/g_85502044.jpg\",\"width\":1900,\"height\":1425,\"caption\":\"Eclisse de suspension KBK A12\\\/16\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/produit\\\/suspension-plate-kbk-a12-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Suspension plate KBK A12\\\/16\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/\",\"name\":\"Ohis\",\"description\":\"Outils de levage\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/#organization\",\"name\":\"Ohis\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-ohis-wit.svg\",\"contentUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-ohis-wit.svg\",\"caption\":\"Ohis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspension plate KBK A12\/16 - Ohis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/","og_locale":"en_US","og_type":"article","og_title":"Suspension plate KBK A12\/16 - Ohis","og_description":"Suspension plate KBK A12\/16","og_url":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/","og_site_name":"Ohis","article_modified_time":"2025-08-25T11:20:26+00:00","og_image":[{"width":1900,"height":1425,"url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/08\/g_85502044.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/","url":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/","name":"Suspension plate KBK A12\/16 - Ohis","isPartOf":{"@id":"https:\/\/www.ohis.be\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/#primaryimage"},"image":{"@id":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/08\/g_85502044.jpg","datePublished":"2025-08-20T13:54:24+00:00","dateModified":"2025-08-25T11:20:26+00:00","breadcrumb":{"@id":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/#primaryimage","url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/08\/g_85502044.jpg","contentUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2025\/08\/g_85502044.jpg","width":1900,"height":1425,"caption":"Eclisse de suspension KBK A12\/16"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ohis.be\/en\/produit\/suspension-plate-kbk-a12-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ohis.be\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.ohis.be\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Suspension plate KBK A12\/16"}]},{"@type":"WebSite","@id":"https:\/\/www.ohis.be\/en\/#website","url":"https:\/\/www.ohis.be\/en\/","name":"Ohis","description":"Outils de levage","publisher":{"@id":"https:\/\/www.ohis.be\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ohis.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ohis.be\/en\/#organization","name":"Ohis","url":"https:\/\/www.ohis.be\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ohis.be\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2021\/02\/logo-ohis-wit.svg","contentUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2021\/02\/logo-ohis-wit.svg","caption":"Ohis"},"image":{"@id":"https:\/\/www.ohis.be\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/product\/84768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/media\/84244"}],"wp:attachment":[{"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/media?parent=84768"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/product_brand?post=84768"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/product_cat?post=84768"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ohis.be\/en\/wp-json\/wp\/v2\/product_tag?post=84768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}