{"id":24195,"date":"2023-01-05T14:38:49","date_gmt":"2023-01-05T13:38:49","guid":{"rendered":"https:\/\/www.ohis.be\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/"},"modified":"2023-01-05T14:38:49","modified_gmt":"2023-01-05T13:38:49","slug":"hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2","status":"publish","type":"product","link":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/","title":{"rendered":"HWPHP Werkstattpresse mit hydraulischer Handpumpe"},"content":{"rendered":"<p>Zum Ein- und Auspressen von Lagern und Buchsen, Pressen und Biegen von Bauteilen, zum Bearbeiten von Wellen und f\u00fcr Richtarbeiten geeignet.<\/p>\n<p>Ausstattung und Verarbeitung<br \/>\n\u2022 Ausf\u00fchrung 15 t und 20 t mit Auflageplatte, Prismensatz und Zentriervorrichtung (Zubeh\u00f6r bei h\u00f6heren Tonnagen optional).<br \/>\n\u2022 Ausgestattet mit zweistufiger Handpumpe.<br \/>\n\u2022 Serienm\u00e4\u00dfig mit Manometer.<br \/>\n\u2022 Mit Handseilwinde zur Tischverstellung (ab HWPHP 30).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum Ein- und Auspressen von Lagern und Buchsen, Pressen und Biegen von Bauteilen, zum Bearbeiten von Wellen und f\u00fcr Richtarbeiten geeignet.<\/p>\n<p>Ausstattung und Verarbeitung<br \/>\n\u2022 Ausf\u00fchrung 15 t und 20 t mit Auflageplatte, Prismensatz und Zentriervorrichtung (Zubeh\u00f6r bei h\u00f6heren Tonnagen optional).<br \/>\n\u2022 Ausgestattet mit zweistufiger Handpumpe.<br \/>\n\u2022 Serienm\u00e4\u00dfig mit Manometer.<br \/>\n\u2022 Mit Handseilwinde zur Tischverstellung (ab HWPHP 30).<\/p>\n","protected":false},"featured_media":23358,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[1609],"product_tag":[1673],"class_list":{"0":"post-24195","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-werkstattpressen","7":"product_tag-pfaff-de","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HWPHP Werkstattpresse mit hydraulischer Handpumpe - Ohis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HWPHP Werkstattpresse mit hydraulischer Handpumpe - Ohis\" \/>\n<meta property=\"og:description\" content=\"Zum Ein- und Auspressen von Lagern und Buchsen, Pressen und Biegen von Bauteilen, zum Bearbeiten von Wellen und f\u00fcr Richtarbeiten geeignet.  Ausstattung und Verarbeitung \u2022 Ausf\u00fchrung 15 t und 20 t mit Auflageplatte, Prismensatz und Zentriervorrichtung (Zubeh\u00f6r bei h\u00f6heren Tonnagen optional). \u2022 Ausgestattet mit zweistufiger Handpumpe. \u2022 Serienm\u00e4\u00dfig mit Manometer. \u2022 Mit Handseilwinde zur Tischverstellung (ab HWPHP 30).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ohis\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ohis.be\/wp-content\/uploads\/2023\/01\/hwphp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"519\" \/>\n\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/\",\"name\":\"HWPHP Werkstattpresse mit hydraulischer Handpumpe - Ohis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hwphp.jpg\",\"datePublished\":\"2023-01-05T13:38:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hwphp.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hwphp.jpg\",\"width\":519,\"height\":851},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produit\\\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HWPHP Werkstattpresse mit hydraulischer Handpumpe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/\",\"name\":\"Ohis\",\"description\":\"Outils de levage\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/#organization\",\"name\":\"Ohis\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-ohis-wit.svg\",\"contentUrl\":\"https:\\\/\\\/www.ohis.be\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-ohis-wit.svg\",\"caption\":\"Ohis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ohis.be\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HWPHP Werkstattpresse mit hydraulischer Handpumpe - Ohis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/","og_locale":"de_DE","og_type":"article","og_title":"HWPHP Werkstattpresse mit hydraulischer Handpumpe - Ohis","og_description":"Zum Ein- und Auspressen von Lagern und Buchsen, Pressen und Biegen von Bauteilen, zum Bearbeiten von Wellen und f\u00fcr Richtarbeiten geeignet.  Ausstattung und Verarbeitung \u2022 Ausf\u00fchrung 15 t und 20 t mit Auflageplatte, Prismensatz und Zentriervorrichtung (Zubeh\u00f6r bei h\u00f6heren Tonnagen optional). \u2022 Ausgestattet mit zweistufiger Handpumpe. \u2022 Serienm\u00e4\u00dfig mit Manometer. \u2022 Mit Handseilwinde zur Tischverstellung (ab HWPHP 30).","og_url":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/","og_site_name":"Ohis","og_image":[{"width":519,"height":851,"url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2023\/01\/hwphp.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/","url":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/","name":"HWPHP Werkstattpresse mit hydraulischer Handpumpe - Ohis","isPartOf":{"@id":"https:\/\/www.ohis.be\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/#primaryimage"},"image":{"@id":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2023\/01\/hwphp.jpg","datePublished":"2023-01-05T13:38:49+00:00","breadcrumb":{"@id":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/#primaryimage","url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2023\/01\/hwphp.jpg","contentUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2023\/01\/hwphp.jpg","width":519,"height":851},{"@type":"BreadcrumbList","@id":"https:\/\/www.ohis.be\/de\/produit\/hwphp-werkstattpresse-mit-hydraulischer-handpumpe-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ohis.be\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/www.ohis.be\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"HWPHP Werkstattpresse mit hydraulischer Handpumpe"}]},{"@type":"WebSite","@id":"https:\/\/www.ohis.be\/de\/#website","url":"https:\/\/www.ohis.be\/de\/","name":"Ohis","description":"Outils de levage","publisher":{"@id":"https:\/\/www.ohis.be\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ohis.be\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.ohis.be\/de\/#organization","name":"Ohis","url":"https:\/\/www.ohis.be\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ohis.be\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ohis.be\/wp-content\/uploads\/2021\/02\/logo-ohis-wit.svg","contentUrl":"https:\/\/www.ohis.be\/wp-content\/uploads\/2021\/02\/logo-ohis-wit.svg","caption":"Ohis"},"image":{"@id":"https:\/\/www.ohis.be\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/product\/24195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/media\/23358"}],"wp:attachment":[{"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/media?parent=24195"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/product_brand?post=24195"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/product_cat?post=24195"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ohis.be\/de\/wp-json\/wp\/v2\/product_tag?post=24195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}